{"id":9465,"date":"2021-06-25T12:03:37","date_gmt":"2021-06-25T10:03:37","guid":{"rendered":"https:\/\/lapoderosagoods.spainmotoexperiences.es\/producto\/support-de-sacoche-des-deux-cotes-r1150gs-satin-black\/"},"modified":"2026-06-26T11:28:47","modified_gmt":"2026-06-26T09:28:47","slug":"support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black","status":"publish","type":"product","link":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/","title":{"rendered":"Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black"},"content":{"rendered":"<div class=\"product-single__description rte\">\n<p class=\"s3\"><span class=\"s2\">Cadres double \u00a0en acier finition noir satin\u00e9 pour BMW R1150GS .<\/span><\/p>\n<p class=\"s3\"><span class=\"s2\">Pi\u00e9ces con\u00e7ues pour se boulonner sur le sous-ch\u00e2ssis arri\u00e8re de tout \u00a0Bmw R1150 gs *\u00a0 <\/span><span class=\"s2\">par vis.\u00a0<\/span><\/p>\n<p class=\"s3\">Peint avec une peinture en poudre \u00e1 haute r\u00e9sistance de couleur noir satin\u00e9.<\/p>\n<p class=\"s3\"><span class=\"s2\">\u00a0Classic<\/span><span class=\"s2\">\u00a0et minimaliste, parfait m\u00eame avec le sac lat\u00e9ral retir\u00e9.<\/span><\/p>\n<p class=\"s3\"><span class=\"s2\">Structure tr\u00e8s solide pour des charges jusqu&rsquo;\u00e0 10kg par sac.<\/span><\/p>\n<p class=\"s3\"><span class=\"s2\">* Compatible avec les mod\u00e8les suivants :<\/span><\/p>\n<p class=\"s3\"><span class=\"s2\">R1150GS<\/span><\/p>\n<p class=\"s3\"><span class=\"s2\">R1150GS ADV<\/span><\/p>\n<p>R850 GS<\/p>\n<p>R1100 GS<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cadres double \u00a0en acier finition noir satin\u00e9 pour BMW R1150GS . Pi\u00e9ces con\u00e7ues pour se boulonner sur le sous-ch\u00e2ssis arri\u00e8re de tout \u00a0Bmw R1150 gs *\u00a0 par vis.\u00a0 Peint avec une peinture en poudre \u00e1 haute r\u00e9sistance de couleur noir satin\u00e9. \u00a0Classic\u00a0et minimaliste, parfait m\u00eame avec le sac lat\u00e9ral retir\u00e9. Structure tr\u00e8s solide pour des [&#8230;]\n","protected":false},"featured_media":16088,"comment_status":"closed","ping_status":"closed","template":"","meta":{"spay_email":""},"product_cat":[695,127,115],"product_tag":[440],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black - La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black - La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme\" \/>\n<meta property=\"og:description\" content=\"Cadres double \u00a0en acier finition noir satin\u00e9 pour BMW R1150GS . Pi\u00e9ces con\u00e7ues pour se boulonner sur le sous-ch\u00e2ssis arri\u00e8re de tout \u00a0Bmw R1150 gs *\u00a0 par vis.\u00a0 Peint avec une peinture en poudre \u00e1 haute r\u00e9sistance de couleur noir satin\u00e9. \u00a0Classic\u00a0et minimaliste, parfait m\u00eame avec le sac lat\u00e9ral retir\u00e9. Structure tr\u00e8s solide pour des [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/\" \/>\n<meta property=\"og:site_name\" content=\"La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T09:28:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/lapoderosagoods.com\/#organization\",\"name\":\"La Poderosa Classic Goods\",\"url\":\"https:\/\/lapoderosagoods.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/lapoderosagoods.com\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2019\/10\/poderosa.png\",\"contentUrl\":\"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2019\/10\/poderosa.png\",\"width\":290,\"height\":209,\"caption\":\"La Poderosa Classic Goods\"},\"image\":{\"@id\":\"https:\/\/lapoderosagoods.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lapoderosagoods.com\/#website\",\"url\":\"https:\/\/lapoderosagoods.com\/\",\"name\":\"La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme\",\"description\":\"Bagages, supports, sacoches et accessoires pour les motos classiques, caf\\u00e9 racer ou d'aventure. \",\"publisher\":{\"@id\":\"https:\/\/lapoderosagoods.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lapoderosagoods.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg\",\"contentUrl\":\"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#webpage\",\"url\":\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/\",\"name\":\"Support de sacoche double (des deux c\\u00f4t\\u00e9s) R1150GS Satin Black - La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme\",\"isPartOf\":{\"@id\":\"https:\/\/lapoderosagoods.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#primaryimage\"},\"datePublished\":\"2021-06-25T10:03:37+00:00\",\"dateModified\":\"2026-06-26T09:28:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lapoderosagoods.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/lapoderosagoods.com\/fr\/produits\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Support de sacoche double (des deux c\\u00f4t\\u00e9s) R1150GS Satin Black\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black - La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/","og_locale":"fr_FR","og_type":"article","og_title":"Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black - La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme","og_description":"Cadres double \u00a0en acier finition noir satin\u00e9 pour BMW R1150GS . Pi\u00e9ces con\u00e7ues pour se boulonner sur le sous-ch\u00e2ssis arri\u00e8re de tout \u00a0Bmw R1150 gs *\u00a0 par vis.\u00a0 Peint avec une peinture en poudre \u00e1 haute r\u00e9sistance de couleur noir satin\u00e9. \u00a0Classic\u00a0et minimaliste, parfait m\u00eame avec le sac lat\u00e9ral retir\u00e9. Structure tr\u00e8s solide pour des [...]","og_url":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/","og_site_name":"La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme","article_modified_time":"2026-06-26T09:28:47+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg","path":"\/home\/spainmot\/lapoderosagoods\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg","size":"full","id":16088,"alt":"","pixels":4915200,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/lapoderosagoods.com\/#organization","name":"La Poderosa Classic Goods","url":"https:\/\/lapoderosagoods.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/lapoderosagoods.com\/#logo","inLanguage":"fr-FR","url":"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2019\/10\/poderosa.png","contentUrl":"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2019\/10\/poderosa.png","width":290,"height":209,"caption":"La Poderosa Classic Goods"},"image":{"@id":"https:\/\/lapoderosagoods.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/lapoderosagoods.com\/#website","url":"https:\/\/lapoderosagoods.com\/","name":"La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme","description":"Bagages, supports, sacoches et accessoires pour les motos classiques, caf\u00e9 racer ou d'aventure. ","publisher":{"@id":"https:\/\/lapoderosagoods.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lapoderosagoods.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg","contentUrl":"https:\/\/lapoderosagoods.com\/wp-content\/uploads\/2021\/06\/Bmw-R1150-adv-rack-LHS--scaled.jpg","width":2560,"height":1920},{"@type":"WebPage","@id":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#webpage","url":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/","name":"Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black - La Poderosa Goods - Sacoches de selle, bagages et accessoires de moto haut de gamme","isPartOf":{"@id":"https:\/\/lapoderosagoods.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#primaryimage"},"datePublished":"2021-06-25T10:03:37+00:00","dateModified":"2026-06-26T09:28:47+00:00","breadcrumb":{"@id":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lapoderosagoods.com\/fr\/produit\/support-de-sacoche-double-des-deux-cotes-r1150gs-satin-black\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lapoderosagoods.com\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/lapoderosagoods.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Support de sacoche double (des deux c\u00f4t\u00e9s) R1150GS Satin Black"}]}]}},"_links":{"self":[{"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/product\/9465"}],"collection":[{"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/comments?post=9465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/media\/16088"}],"wp:attachment":[{"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/media?parent=9465"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/product_cat?post=9465"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lapoderosagoods.com\/fr\/wp-json\/wp\/v2\/product_tag?post=9465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}